{"id":3179,"date":"2017-06-19T18:33:35","date_gmt":"2017-06-19T18:33:35","guid":{"rendered":"http:\/\/kilim-age.com\/?post_type=product&#038;p=3179"},"modified":"2025-06-20T14:18:31","modified_gmt":"2025-06-20T12:18:31","slug":"blue-patchwork-carpet-191-x-122-cm","status":"publish","type":"product","link":"https:\/\/kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/","title":{"rendered":"ALFOMBRA PATCHWORK AZUL 191 X 122 cm"},"content":{"rendered":"<h3><strong>ALFOMBRAS PATCHWORK<\/strong><\/h3>\n<p>La palabra patchwork viene del ingl\u00e9s \u201cpatch\u201d (parche) y \u201cwork\u201d (trabajo). Conocido tambi\u00e9n como \u201cpieced work\u201d, se trata de la uni\u00f3n de muchas piezas diferentes, alternando incluso colores y tejidos. Literalmente significa trabajo con parches o remiendos. Esta t\u00e9cnica textil permite confeccionar piezas uniendo fragmentos de telas de diferentes tipos y colores. Dicho de otro modo, es una forma de costura que consiste en coser o ensamblar distintas trozos de tela formando otra tela o un dise\u00f1o m\u00e1s grande.<\/p>\n<p>La alfombra Patchwork est\u00e1 hecha con retazos de alfombras de vintage hechos a mano que aproximadamente suelen tener entre 20-30 a\u00f1os de antig\u00fcedad. Se trata de crear una alfombra a partir de parches de diferentes alfombras. Gracias a las t\u00e9cnicas utilizadas para las alfombras vintage, podemos conseguir una gama muy amplia de colores naturales. Suponen una segunda vida para las alfombras y una manera novedosa y original de utilizarlas. El tradicional m\u00e9todo mosaico de los patchwork permite que las alfombras sean elaboradas en los tama\u00f1os deseados por cada cliente. Pueden personalizarse y hacer a medida tanto las medidas de la alfombra, como la de los parches que la componen. Todas nuestras alfombras de patchwork est\u00e1n elaboradas artesanalmente con los materiales de alta calidad y originarios de Turqu\u00eda.<\/p>\n<p>Como objeto de decoraci\u00f3n supone un elemento \u00fanico y especial, adem\u00e1s de personalizado. Tambi\u00e9n ofrece una variedad de colores y combinaciones mucho m\u00e1s amplia de la que ten\u00edamos con las alfombras cl\u00e1sicas. Suelen utilizarse en todo tipo de ambientes y actualmente son las alfombras por excelencia de todos los estilos en tendencia.","protected":false},"excerpt":{"rendered":"<p>Fabricaci\u00f3n: Hecho a mano<br \/>\nTama\u00f1o:191 X 122 cm.<br \/>\nN\u00famero de nudos: aprox 150000-300000 por m\u00b2<br \/>\nEstado: Nuevo<br \/>\nOrigen: Turqu\u00eda<br \/>\nPelo: Lana<br \/>\nUrdimbre: Algod\u00f3n<br \/>\nGrosor aprox: 7-8 mm.<br \/>\nTe\u00f1ido natural.<br \/>\nLos colores de la alfombra se percibir\u00e1n de formas diferentes dependiendo del \u00e1ngulo de visi\u00f3n.<br \/>\nPlazo de entrega: 2-5 d\u00edas h\u00e1biles en Espa\u00f1a.<br \/>\nEuropa: 5-7 d\u00edas h\u00e1biles, resto de continentes 7-10 d\u00edas.<\/p>\n","protected":false},"featured_media":3180,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[62,224],"product_tag":[67,94],"class_list":{"0":"post-3179","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alfombras-turcas","7":"product_cat-alfombras-patchwork","8":"product_tag-alfombra-patchwork","9":"product_tag-patchwork-carpets","10":"product_shipping_class-alfombra-pequena","11":"pa_medida-medianos","13":"first","14":"outofstock","15":"sale","16":"sold-individually","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ALFOMBRA PATCHWORK AZUL 191 X 122 cm | Kilim-Age<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALFOMBRA PATCHWORK AZUL 191 X 122 cm | Kilim-Age\" \/>\n<meta property=\"og:description\" content=\"Fabricaci\u00f3n: Hecho a mano Tama\u00f1o:191 X 122 cm. N\u00famero de nudos: aprox 150000-300000 por m\u00b2 Estado: Nuevo Origen: Turqu\u00eda Pelo: Lana Urdimbre: Algod\u00f3n Grosor aprox: 7-8 mm. Te\u00f1ido natural. Los colores de la alfombra se percibir\u00e1n de formas diferentes dependiendo del \u00e1ngulo de visi\u00f3n. Plazo de entrega: 2-5 d\u00edas h\u00e1biles en Espa\u00f1a. Europa: 5-7 d\u00edas h\u00e1biles, resto de continentes 7-10 d\u00edas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/\" \/>\n<meta property=\"og:site_name\" content=\"Kilim-Age\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-20T12:18:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.kilim-age.com\/wp-content\/uploads\/2017\/06\/WEB-KA_6631.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/\",\"url\":\"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/\",\"name\":\"ALFOMBRA PATCHWORK AZUL 191 X 122 cm | Kilim-Age\",\"isPartOf\":{\"@id\":\"https:\/\/kilim-age.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kilim-age.com\/wp-content\/uploads\/2017\/06\/WEB-KA_6631.jpg\",\"datePublished\":\"2017-06-19T18:33:35+00:00\",\"dateModified\":\"2025-06-20T12:18:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/#primaryimage\",\"url\":\"https:\/\/kilim-age.com\/wp-content\/uploads\/2017\/06\/WEB-KA_6631.jpg\",\"contentUrl\":\"https:\/\/kilim-age.com\/wp-content\/uploads\/2017\/06\/WEB-KA_6631.jpg\",\"width\":1000,\"height\":1300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.kilim-age.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.kilim-age.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ALFOMBRA PATCHWORK AZUL 191 X 122 cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kilim-age.com\/en\/#website\",\"url\":\"https:\/\/kilim-age.com\/en\/\",\"name\":\"Kilim-Age\",\"description\":\"Somos especialistas en productos artesanales de Turqu\u00eda como Alfombras, y Kilims\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kilim-age.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ALFOMBRA PATCHWORK AZUL 191 X 122 cm | Kilim-Age","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/","og_locale":"es_ES","og_type":"article","og_title":"ALFOMBRA PATCHWORK AZUL 191 X 122 cm | Kilim-Age","og_description":"Fabricaci\u00f3n: Hecho a mano Tama\u00f1o:191 X 122 cm. N\u00famero de nudos: aprox 150000-300000 por m\u00b2 Estado: Nuevo Origen: Turqu\u00eda Pelo: Lana Urdimbre: Algod\u00f3n Grosor aprox: 7-8 mm. Te\u00f1ido natural. Los colores de la alfombra se percibir\u00e1n de formas diferentes dependiendo del \u00e1ngulo de visi\u00f3n. Plazo de entrega: 2-5 d\u00edas h\u00e1biles en Espa\u00f1a. Europa: 5-7 d\u00edas h\u00e1biles, resto de continentes 7-10 d\u00edas.","og_url":"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/","og_site_name":"Kilim-Age","article_modified_time":"2025-06-20T12:18:31+00:00","og_image":[{"width":1000,"height":1300,"url":"https:\/\/www.kilim-age.com\/wp-content\/uploads\/2017\/06\/WEB-KA_6631.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/","url":"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/","name":"ALFOMBRA PATCHWORK AZUL 191 X 122 cm | Kilim-Age","isPartOf":{"@id":"https:\/\/kilim-age.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/#primaryimage"},"image":{"@id":"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/#primaryimage"},"thumbnailUrl":"https:\/\/kilim-age.com\/wp-content\/uploads\/2017\/06\/WEB-KA_6631.jpg","datePublished":"2017-06-19T18:33:35+00:00","dateModified":"2025-06-20T12:18:31+00:00","breadcrumb":{"@id":"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/#primaryimage","url":"https:\/\/kilim-age.com\/wp-content\/uploads\/2017\/06\/WEB-KA_6631.jpg","contentUrl":"https:\/\/kilim-age.com\/wp-content\/uploads\/2017\/06\/WEB-KA_6631.jpg","width":1000,"height":1300},{"@type":"BreadcrumbList","@id":"https:\/\/www.kilim-age.com\/es\/producto\/blue-patchwork-carpet-191-x-122-cm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kilim-age.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.kilim-age.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"ALFOMBRA PATCHWORK AZUL 191 X 122 cm"}]},{"@type":"WebSite","@id":"https:\/\/kilim-age.com\/en\/#website","url":"https:\/\/kilim-age.com\/en\/","name":"Kilim-Age","description":"Somos especialistas en productos artesanales de Turqu\u00eda como Alfombras, y Kilims","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kilim-age.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/product\/3179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/comments?post=3179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/media\/3180"}],"wp:attachment":[{"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/media?parent=3179"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/product_brand?post=3179"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/product_cat?post=3179"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/product_tag?post=3179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}