{"id":19104,"date":"2021-06-07T18:36:33","date_gmt":"2021-06-07T16:36:33","guid":{"rendered":"http:\/\/kilim-age.com\/?post_type=product&#038;p=19104"},"modified":"2025-06-14T17:28:08","modified_gmt":"2025-06-14T15:28:08","slug":"kilim-moderno-283-x-94-cm","status":"publish","type":"product","link":"https:\/\/kilim-age.com\/es\/producto\/kilim-moderno-283-x-94-cm\/","title":{"rendered":"KILIM MODERNO 283 X 94 cm"},"content":{"rendered":"Alfombra tipo Kilim 100% lana con dise\u00f1o moderno. Es una pieza tejida a mano en Usak sobre base de color beige y dibujos color marr\u00f3n. No existen dos piezas iguales, sus medidas son 283 x 94 cm. Es ideal para delimitar espacios en salones o en habitaciones. Su dise\u00f1o original y moderna crea un ambiente de inspiraci\u00f3n oriental muy \u00e9tnico, acogedor y c\u00e1lido. Se puede utilizar todo el a\u00f1o, gracias a la lana, material aislante tanto del fr\u00edo como del calor. Es una pieza perfecta para cualquier estaci\u00f3n.<\/p>\n<h1>KILIM Y SU HISTORIA<\/h1>\n<p>El kilim es un tejido simple con un urdimbre y tramo. B\u00e1sicamente se distingue por no tener \u201cpelos\u201d como la alfombra.<br \/>\nNacieron hace unos 3.500 a\u00f1os en Asia Central, desde donde se fueron extendiendo hacia Europa Oriental, \u00c1frica del Norte y m\u00e1s tarde Europa Occidental. Son consideradas, por tanto, las alfombras m\u00e1s antiguas del mundo. El origen n\u00f3mada de quienes lo usaban en la antig\u00fcedad, hicieron que tuviesen una caracter\u00edstica especial en la trama de urdimbre, plana y sin nudos, para evitar el paso de la arena del desierto, ya que acompa\u00f1aban a sus due\u00f1os como maletas o como divisorios en las tiendas que armaban en los viajes. Los dise\u00f1os estaban llenos de simbolismo, de deseos, de mensajes o de pedidos por ejemplo los motivos con forma de S anunciaban un feliz acontecimiento. En general se confeccionaban sin un patr\u00f3n previo que los daba espontaneidad y exclusividad a cada pieza, los actuales no respetan a estos tradiciones pero mantienen el esp\u00edritu \u00e1gil del tejido original.<br \/>\nUna de las principales ventajas del kilim es pesa muy poco, es liviana y nos transmite una imagen fresca y ligera.","protected":false},"excerpt":{"rendered":"<p>Fabricaci\u00f3n: Hecho a mano<br \/>\nTama\u00f1o: 283 X 94 cm<br \/>\nEstado: Producci\u00f3n nuevo<br \/>\nOrigen: Turqu\u00eda, Usak<br \/>\nMaterial: Lana<br \/>\nGrosor aprox: 2-3 mm<br \/>\nTe\u00f1ido con colores naturales<br \/>\nLos colores se percibir\u00e1n de formas diferentes dependiendo del \u00e1ngulo de visi\u00f3n<br \/>\nPlazo de entrega: 2-5 d\u00edas h\u00e1biles en Espa\u00f1a peninsular.<br \/>\nEuropa: 5-7 d\u00edas h\u00e1biles, resto de continentes 7-10 d\u00edas.<\/p>\n","protected":false},"featured_media":30140,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[61,829],"product_tag":[73,72,784,74],"class_list":{"0":"post-19104","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kilims","7":"product_cat-toda-la-coleccion-kilim","8":"product_tag-anatolian-kilim","9":"product_tag-kilim","10":"product_tag-kilim-modenro","11":"product_tag-kilim-turca","12":"product_shipping_class-kilim-mediano","13":"pa_ancho-cm-905","14":"pa_largo-cm-906","15":"pa_medida-pequenos","17":"first","18":"instock","19":"sale","20":"sold-individually","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>KILIM MODERNO 283 X 94 cm  | Kilim-Age<\/title>\n<meta name=\"description\" content=\"Alfombra tipo Kilim 100% lana con dise\u00f1o moderno. Es una pieza tejida a mano\u00a0 sobre base color beige y dibujos color marr\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kilim-age.com\/es\/producto\/kilim-moderno-283-x-94-cm\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KILIM MODERNO 283 X 94 cm  | Kilim-Age\" \/>\n<meta property=\"og:description\" content=\"Alfombra tipo Kilim 100% lana con dise\u00f1o moderno. Es una pieza tejida a mano\u00a0 sobre base color beige y dibujos color marr\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/\" \/>\n<meta property=\"og:site_name\" content=\"Kilim-Age\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-14T15:28:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/06\/IMG_08851.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/\",\"url\":\"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/\",\"name\":\"KILIM MODERNO 283 X 94 cm  | Kilim-Age\",\"isPartOf\":{\"@id\":\"https:\/\/kilim-age.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/06\/IMG_08851.jpg\",\"datePublished\":\"2021-06-07T16:36:33+00:00\",\"dateModified\":\"2025-06-14T15:28:08+00:00\",\"description\":\"Alfombra tipo Kilim 100% lana con dise\u00f1o moderno. Es una pieza tejida a mano\u00a0 sobre base color beige y dibujos color marr\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/#primaryimage\",\"url\":\"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/06\/IMG_08851.jpg\",\"contentUrl\":\"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/06\/IMG_08851.jpg\",\"width\":1000,\"height\":1300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.kilim-age.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.kilim-age.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MODERN KILIM 283 X 94 cm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kilim-age.com\/en\/#website\",\"url\":\"https:\/\/kilim-age.com\/en\/\",\"name\":\"Kilim-Age\",\"description\":\"Somos especialistas en productos artesanales de Turqu\u00eda como Alfombras, y Kilims\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kilim-age.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KILIM MODERNO 283 X 94 cm  | Kilim-Age","description":"Alfombra tipo Kilim 100% lana con dise\u00f1o moderno. Es una pieza tejida a mano\u00a0 sobre base color beige y dibujos color marr\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kilim-age.com\/es\/producto\/kilim-moderno-283-x-94-cm\/","og_locale":"es_ES","og_type":"article","og_title":"KILIM MODERNO 283 X 94 cm  | Kilim-Age","og_description":"Alfombra tipo Kilim 100% lana con dise\u00f1o moderno. Es una pieza tejida a mano\u00a0 sobre base color beige y dibujos color marr\u00f3n.","og_url":"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/","og_site_name":"Kilim-Age","article_modified_time":"2025-06-14T15:28:08+00:00","og_image":[{"width":1000,"height":1300,"url":"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/06\/IMG_08851.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/","url":"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/","name":"KILIM MODERNO 283 X 94 cm  | Kilim-Age","isPartOf":{"@id":"https:\/\/kilim-age.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/#primaryimage"},"image":{"@id":"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/#primaryimage"},"thumbnailUrl":"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/06\/IMG_08851.jpg","datePublished":"2021-06-07T16:36:33+00:00","dateModified":"2025-06-14T15:28:08+00:00","description":"Alfombra tipo Kilim 100% lana con dise\u00f1o moderno. Es una pieza tejida a mano\u00a0 sobre base color beige y dibujos color marr\u00f3n.","breadcrumb":{"@id":"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/#primaryimage","url":"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/06\/IMG_08851.jpg","contentUrl":"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/06\/IMG_08851.jpg","width":1000,"height":1300},{"@type":"BreadcrumbList","@id":"https:\/\/kilim-age.com\/en\/producto\/kilim-moderno-283-x-94-cm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kilim-age.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.kilim-age.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"MODERN KILIM 283 X 94 cm"}]},{"@type":"WebSite","@id":"https:\/\/kilim-age.com\/en\/#website","url":"https:\/\/kilim-age.com\/en\/","name":"Kilim-Age","description":"Somos especialistas en productos artesanales de Turqu\u00eda como Alfombras, y Kilims","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kilim-age.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/product\/19104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/comments?post=19104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/media\/30140"}],"wp:attachment":[{"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/media?parent=19104"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/product_brand?post=19104"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/product_cat?post=19104"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/product_tag?post=19104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}