{"id":17884,"date":"2021-03-02T11:18:00","date_gmt":"2021-03-02T11:18:00","guid":{"rendered":"http:\/\/kilim-age.com\/?post_type=product&#038;p=17884"},"modified":"2025-09-05T13:56:47","modified_gmt":"2025-09-05T11:56:47","slug":"alfombra-moderna-lana-y-seda-de-bambu-dorado","status":"publish","type":"product","link":"https:\/\/kilim-age.com\/es\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/","title":{"rendered":"ALFOMBRA MODERNA LANA Y SEDA DE BAMB\u00da 280 x 201"},"content":{"rendered":"Alfombra artesanal de estilo cl\u00e1sico y moderna fabricada en Turqu\u00eda a mano en lana y seda de bamb\u00fa. Su dise\u00f1o es estilo floral al centro y en los laterales lineas doradas sobre un fondo de color beige claro. Es tejida a mano con el antiguo arte de anudaci\u00f3n. Est\u00e1 disponible en 280X 201 cm. Posee un dise\u00f1o precioso que ofrece sensaci\u00f3n de tranquilidad y paz, as\u00ed como,\u00a0 un tacto suave y agradable que te encantar\u00e1.<\/p>\n<p>Ofrece calidez y viste cualquier espacio para darles consistencia y robustez.\u00a0L\u00facela en tu sal\u00f3n o habitaci\u00f3n en incluso en tu despacho u oficina comercial y embellecer\u00e1s con gran elegancia ese espacio tan importante para ti y tu negocio, de forma moderna y actual.<\/p>\n<p>Esta alfombra turca moderna es parte de nuestro variado stock de colores, tama\u00f1os y dise\u00f1os de <a href=\"http:\/\/kilim-age.com\/es\/categoria-producto\/alfombras-turcas\/alfombras-modernas\/\">alfombras modernas<\/a> que puedes comprar online o f\u00edsicamente en nuestra tienda en las Rozas de Madrid.<\/p>\n<h2><strong>ALFOMBRAS MODERNAS \u00a0<\/strong><\/h2>\n<p>Una alfombra moderna turca tejida de forma semi-manual es una adaptaci\u00f3n de las <a href=\"http:\/\/kilim-age.com\/es\/categoria-producto\/alfombras-turcas\/alfombras-clasicas\/\">alfombras\u00a0cl\u00e1sicas<\/a>\u00a0a las nuevas tendencias y necesidades de dise\u00f1os actuales. \u00a0En el proceso de fabricaci\u00f3n siempre utilizamos materiales naturales de alta calidad.\u00a0Las alfombras modernas, se caracterizan por tener contraste de colores y formas m\u00e1s\u00a0<a href=\"https:\/\/es.wikipedia.org\/wiki\/Abstracci%C3%B3n_(filosof%C3%ADa)\">abstractas<\/a>. Tienen el pelo m\u00e1s corto que las alfombras cl\u00e1sicas de toda la vida, por ello, el tacto es muy suave y agradable. Suponen una nueva corriente para este arte milenario de anudar.<\/p>\n<p>En su composici\u00f3n combinan materiales como algod\u00f3n, lana, seda y viscosa te\u00f1idos en tintes de minerales naturales. As\u00ed mismo, ofrecen un nivel de mantenimiento muy f\u00e1cil y tienen una calidad y resistencia inmejorable.<\/p>\n<h2><strong>\u00bfPOR QUE RECOMENDAMOS COMPRAR UNA ALFOMBRA TURCA MODERNA?<\/strong><\/h2>\n<p>Esta nueva tendencia de alfombras suponen una alternativa para aquellos ambientes m\u00e1s homog\u00e9neos. Son alfombras que se adaptan a espacios de cualquier estilo y dan un toque moderno y original. Dan una nota art\u00edstica al ambiente que queremos crear. Ofrecen calidez y visten los espacios para darles consistencia y robustez.","protected":false},"excerpt":{"rendered":"<p>Fabricaci\u00f3n: Tejido a mano<br \/>\nTama\u00f1o: 280&#215;201<br \/>\nN\u00famero de nudos: aprox 120000 por m\u00b2<br \/>\nEstado: Nuevo<br \/>\nOrigen: Hecha en Turqu\u00eda<br \/>\nPelo: Lana y seda de bamb\u00fa<br \/>\nUrdimbre: algod\u00f3n<br \/>\nGrosor aprox: 6-7 mm<br \/>\nTodas nuestras alfombras modernas est\u00e1n hechas con materiales naturales de alta calidad.<br \/>\nLos colores de la alfombra se percibir\u00e1n de formas diferentes dependiendo del \u00e1ngulo de visi\u00f3n<br \/>\nPlazo de entrega: 2-5 d\u00edas h\u00e1biles en Espa\u00f1a.<br \/>\nEuropa: 5-7 d\u00edas h\u00e1biles, resto de continentes 7-10 d\u00edas.<\/p>\n","protected":false},"featured_media":24969,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[62,230],"product_tag":[852,813,294,803],"class_list":{"0":"post-17884","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alfombras-turcas","7":"product_cat-alfombras-clasicas","8":"product_tag-alfombra-de-lana","9":"product_tag-alfombra-turca","10":"product_tag-alfombras-modernas","11":"product_tag-modern-carpets","12":"product_shipping_class-alfombra-grande","13":"pa_ancho-cm-957","14":"pa_color-dorado","15":"pa_largo-cm-1011","16":"pa_seleccionar-medidas-120x180-cm","17":"pa_seleccionar-medidas-160x230-cm","18":"pa_seleccionar-medidas-200x300-cm","19":"pa_seleccionar-medidas-240x340-cm","20":"pa_seleccionar-medidas-400x300-cm","21":"pa_seleccionar-medidas-80x150-cm","23":"first","24":"instock","25":"sale","26":"sold-individually","27":"taxable","28":"shipping-taxable","29":"purchasable","30":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>High quality woven blue lines abstract Turkish modern carpet.<\/title>\n<meta name=\"description\" content=\"Modern abstract Turkish rug woven semi-manually with the ancient art of knotting. Made with high quality. Shipments to Spain and the rest of Europe\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kilim-age.com\/es\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"High quality woven blue lines abstract Turkish modern carpet.\" \/>\n<meta property=\"og:description\" content=\"Modern abstract Turkish rug woven semi-manually with the ancient art of knotting. Made with high quality. Shipments to Spain and the rest of Europe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/\" \/>\n<meta property=\"og:site_name\" content=\"Kilim-Age\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-05T11:56:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/03\/IMG_99811.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/\",\"url\":\"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/\",\"name\":\"High quality woven blue lines abstract Turkish modern carpet.\",\"isPartOf\":{\"@id\":\"https:\/\/kilim-age.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/03\/IMG_99811.jpg\",\"datePublished\":\"2021-03-02T11:18:00+00:00\",\"dateModified\":\"2025-09-05T11:56:47+00:00\",\"description\":\"Modern abstract Turkish rug woven semi-manually with the ancient art of knotting. Made with high quality. Shipments to Spain and the rest of Europe\",\"breadcrumb\":{\"@id\":\"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/#primaryimage\",\"url\":\"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/03\/IMG_99811.jpg\",\"contentUrl\":\"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/03\/IMG_99811.jpg\",\"width\":1000,\"height\":1300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.kilim-age.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.kilim-age.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MODERN BAMBOO WOOL AND SILK RUG 280 x 201\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kilim-age.com\/en\/#website\",\"url\":\"https:\/\/kilim-age.com\/en\/\",\"name\":\"Kilim-Age\",\"description\":\"Somos especialistas en productos artesanales de Turqu\u00eda como Alfombras, y Kilims\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kilim-age.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"High quality woven blue lines abstract Turkish modern carpet.","description":"Modern abstract Turkish rug woven semi-manually with the ancient art of knotting. Made with high quality. Shipments to Spain and the rest of Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kilim-age.com\/es\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/","og_locale":"es_ES","og_type":"article","og_title":"High quality woven blue lines abstract Turkish modern carpet.","og_description":"Modern abstract Turkish rug woven semi-manually with the ancient art of knotting. Made with high quality. Shipments to Spain and the rest of Europe","og_url":"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/","og_site_name":"Kilim-Age","article_modified_time":"2025-09-05T11:56:47+00:00","og_image":[{"width":1000,"height":1300,"url":"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/03\/IMG_99811.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/","url":"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/","name":"High quality woven blue lines abstract Turkish modern carpet.","isPartOf":{"@id":"https:\/\/kilim-age.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/#primaryimage"},"image":{"@id":"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/#primaryimage"},"thumbnailUrl":"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/03\/IMG_99811.jpg","datePublished":"2021-03-02T11:18:00+00:00","dateModified":"2025-09-05T11:56:47+00:00","description":"Modern abstract Turkish rug woven semi-manually with the ancient art of knotting. Made with high quality. Shipments to Spain and the rest of Europe","breadcrumb":{"@id":"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/#primaryimage","url":"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/03\/IMG_99811.jpg","contentUrl":"https:\/\/kilim-age.com\/wp-content\/uploads\/2021\/03\/IMG_99811.jpg","width":1000,"height":1300},{"@type":"BreadcrumbList","@id":"https:\/\/kilim-age.com\/en\/producto\/alfombra-moderna-lana-y-seda-de-bambu-dorado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kilim-age.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.kilim-age.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"MODERN BAMBOO WOOL AND SILK RUG 280 x 201"}]},{"@type":"WebSite","@id":"https:\/\/kilim-age.com\/en\/#website","url":"https:\/\/kilim-age.com\/en\/","name":"Kilim-Age","description":"Somos especialistas en productos artesanales de Turqu\u00eda como Alfombras, y Kilims","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kilim-age.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/product\/17884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/comments?post=17884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/media\/24969"}],"wp:attachment":[{"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/media?parent=17884"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/product_brand?post=17884"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/product_cat?post=17884"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kilim-age.com\/es\/wp-json\/wp\/v2\/product_tag?post=17884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}