{"id":308,"count":3,"description":"","link":"https:\/\/kilim-age.com\/en\/categoria-producto\/kilim-shoes\/modelos-unisex\/talla-39-modelos-unisex\/","name":"Size 39","slug":"talla-39-modelos-unisex","taxonomy":"product_cat","parent":303,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Size 39 | Kilim-Age<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kilim-age.com\/en\/categoria-producto\/kilim-shoes\/modelos-unisex\/talla-39-modelos-unisex\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Size 39 | Kilim-Age\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kilim-age.com\/en\/categoria-producto\/kilim-shoes\/modelos-unisex\/talla-39-modelos-unisex\/\" \/>\n<meta property=\"og:site_name\" content=\"Kilim-Age\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/kilim-age.com\/en\/categoria-producto\/kilim-shoes\/modelos-unisex\/talla-39-modelos-unisex\/\",\"url\":\"https:\/\/kilim-age.com\/en\/categoria-producto\/kilim-shoes\/modelos-unisex\/talla-39-modelos-unisex\/\",\"name\":\"Size 39 | Kilim-Age\",\"isPartOf\":{\"@id\":\"https:\/\/kilim-age.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/kilim-age.com\/en\/categoria-producto\/kilim-shoes\/modelos-unisex\/talla-39-modelos-unisex\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kilim-age.com\/en\/categoria-producto\/kilim-shoes\/modelos-unisex\/talla-39-modelos-unisex\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.kilim-age.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KILIM SHOES\",\"item\":\"https:\/\/www.kilim-age.com\/en\/categoria-producto\/kilim-shoes\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Modelos Unisex\",\"item\":\"https:\/\/www.kilim-age.com\/es\/categoria-producto\/kilim-shoes\/modelos-unisex\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Size 39\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kilim-age.com\/en\/#website\",\"url\":\"https:\/\/kilim-age.com\/en\/\",\"name\":\"Kilim-Age\",\"description\":\"Somos especialistas en productos artesanales de Turqu\u00eda como Alfombras, y Kilims\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kilim-age.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Size 39 | Kilim-Age","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kilim-age.com\/en\/categoria-producto\/kilim-shoes\/modelos-unisex\/talla-39-modelos-unisex\/","og_locale":"en_US","og_type":"article","og_title":"Size 39 | Kilim-Age","og_url":"https:\/\/kilim-age.com\/en\/categoria-producto\/kilim-shoes\/modelos-unisex\/talla-39-modelos-unisex\/","og_site_name":"Kilim-Age","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/kilim-age.com\/en\/categoria-producto\/kilim-shoes\/modelos-unisex\/talla-39-modelos-unisex\/","url":"https:\/\/kilim-age.com\/en\/categoria-producto\/kilim-shoes\/modelos-unisex\/talla-39-modelos-unisex\/","name":"Size 39 | Kilim-Age","isPartOf":{"@id":"https:\/\/kilim-age.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/kilim-age.com\/en\/categoria-producto\/kilim-shoes\/modelos-unisex\/talla-39-modelos-unisex\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/kilim-age.com\/en\/categoria-producto\/kilim-shoes\/modelos-unisex\/talla-39-modelos-unisex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kilim-age.com\/en\/"},{"@type":"ListItem","position":2,"name":"KILIM SHOES","item":"https:\/\/www.kilim-age.com\/en\/categoria-producto\/kilim-shoes\/"},{"@type":"ListItem","position":3,"name":"Modelos Unisex","item":"https:\/\/www.kilim-age.com\/es\/categoria-producto\/kilim-shoes\/modelos-unisex\/"},{"@type":"ListItem","position":4,"name":"Size 39"}]},{"@type":"WebSite","@id":"https:\/\/kilim-age.com\/en\/#website","url":"https:\/\/kilim-age.com\/en\/","name":"Kilim-Age","description":"Somos especialistas en productos artesanales de Turqu\u00eda como Alfombras, y Kilims","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kilim-age.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/kilim-age.com\/en\/wp-json\/wp\/v2\/product_cat\/308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kilim-age.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/kilim-age.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/kilim-age.com\/en\/wp-json\/wp\/v2\/product_cat\/303"}],"wp:post_type":[{"href":"https:\/\/kilim-age.com\/en\/wp-json\/wp\/v2\/product?product_cat=308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}